{"id":95365,"date":"2024-04-04T08:00:57","date_gmt":"2024-04-04T06:00:57","guid":{"rendered":"https:\/\/www.zivautomation.com\/?p=95365"},"modified":"2024-04-09T12:34:54","modified_gmt":"2024-04-09T10:34:54","slug":"middle-east-energy-2024","status":"publish","type":"post","link":"https:\/\/www.zivautomation.com\/es\/news-and-events\/eventos\/middle-east-energy-2024\/","title":{"rendered":"\u00a1Conozca el futuro de la automatizaci\u00f3n de la energ\u00eda en MEE &#8211; Middle East Energy 2024!"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text]<\/p>\n<h1 class=\"cvGsUA direction-ltr align-start para-style-body\"><span class=\"OYPEnA text-decoration-none text-strikethrough-none\">\u00daltimas novedades de ZIV a la vanguardia en la automatizaci\u00f3n de alta, media y baja tensi\u00f3n<\/span><\/h1>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text]<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-95367\" src=\"https:\/\/www.zivautomation.com\/wp-content\/uploads\/2024\/04\/mee-post.jpg\" alt=\"Middle East Energy 2024\" width=\"800\" height=\"400\" srcset=\"https:\/\/www.zivautomation.com\/wp-content\/uploads\/2024\/04\/mee-post.jpg 800w, https:\/\/www.zivautomation.com\/wp-content\/uploads\/2024\/04\/mee-post-300x150.jpg 300w, https:\/\/www.zivautomation.com\/wp-content\/uploads\/2024\/04\/mee-post-768x384.jpg 768w, https:\/\/www.zivautomation.com\/wp-content\/uploads\/2024\/04\/mee-post-672x336.jpg 672w, https:\/\/www.zivautomation.com\/wp-content\/uploads\/2024\/04\/mee-post-480x240.jpg 480w, https:\/\/www.zivautomation.com\/wp-content\/uploads\/2024\/04\/mee-post-190x95.jpg 190w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text]ZIV estar\u00e1 presente en Middle East Energy, la feria y conferencia sobre energ\u00eda m\u00e1s importante de la regi\u00f3n. Estaremos a tu disposici\u00f3n para darte a conocer nuestros productos y soluciones m\u00e1s innovadores en el campo la automatizaci\u00f3n de AT, MT y BT,\u00a0 equipos y herramientas que est\u00e1n revolucionando el panorama energ\u00e9tico. A continuaci\u00f3n, una muestra de lo m\u00e1s destacado que se podr\u00e1 encontrar en el stand S1.A10 de Alfanar &#8211; Zona ZIV:<\/p>\n<ul>\n<li><a href=\"https:\/\/www.zivautomation.com\/es\/productos\/comunicaciones\/#Telecomunicaciones%20AT\">Sistemas de Teleprotecci\u00f3n<\/a> mejorados: descubra c\u00f3mo nuestro nuevo sistema de Teleprotecci\u00f3n garantiza una seguridad y fiabilidad avanzadas para su red.<\/li>\n<li>Nueva <a target=\"_blank\" href=\"https:\/\/www.zivautomation.com\/wp-content\/uploads\/2024\/04\/pro-ziv-rtus-.pdf\">ZIV MV Flexible RTU<\/a>: explore la versatilidad y eficiencia de nuestra \u00faltima Unidad Terminal Remota Flexible de Media Tensi\u00f3n y eche un vistazo tambi\u00e9n a nuestro modelo <a href=\"https:\/\/www.zivautomation.com\/es\/productos\/soluciones-de-automatizacion-de-distribucion\/rtu-de-media-tension-adaptado-a-su-utilizacion-en-seccionadores-aereos-ocr\/\">MV RTU &#8211; TCA<\/a> integrado en la nueva RMU- inteligente libre SF6 de Alfanar.<\/li>\n<li>Innovadora plataforma de automatizaci\u00f3n de energ\u00eda ZIV TWINGRID: conozca futuro de la gesti\u00f3n de la energ\u00eda gracias nuestra innovadora plataforma TWINGRID, dise\u00f1ada para optimizar el rendimiento de la red y la integraci\u00f3n de recursos energ\u00e9ticos distribuidos.<\/li>\n<li>Gama de productos de <a href=\"https:\/\/www.zivautomation.com\/es\/productos\/sistemas-de-automatizacion-de-subestacion\/\">Protecci\u00f3n y Control de ZIV<\/a>: profundice en nuestra completa oferta de soluciones de protecci\u00f3n y control y servicios de ingenier\u00eda.<\/li>\n<\/ul>\n<p>No se pierda esta oportunidad de adelantarse a los acontecimientos y dar forma al futuro de la automatizaci\u00f3n de la energ\u00eda con ZIV. \u00a1Nos vemos en el Stand S1.A10 de Alfanar![\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p> \u00daltimas novedades de ZIV a la vanguardia en la automatizaci\u00f3n de alta, media y baja tensi\u00f3n ZIV estar\u00e1 presente en Middle East Energy, la feria y conferencia sobre energ\u00eda m\u00e1s importante de la regi\u00f3n. Estaremos a tu disposici\u00f3n para darte a conocer nuestros productos y soluciones m\u00e1s innovadores en el campo la automatizaci\u00f3n de AT, MT y BT,\u00a0 equipos [&hellip;]<\/p>\n","protected":false},"author":1324,"featured_media":95367,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","footnotes":""},"categories":[78],"tags":[],"class_list":["post-95365","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventos"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00a1Conozca el futuro de la automatizaci\u00f3n de la energ\u00eda en MEE - Middle East Energy 2024! - ZIV<\/title>\n<meta name=\"description\" content=\"Conozca de primera mano nuestras vanguardistas soluciones en automatizaci\u00f3n de AT, MT y BT que est\u00e1n revolucionando el panorama energ\u00e9tico.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.zivautomation.com\/es\/news-and-events\/eventos\/middle-east-energy-2024\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00a1Conozca el futuro de la automatizaci\u00f3n de la energ\u00eda en MEE - Middle East Energy 2024! - ZIV\" \/>\n<meta property=\"og:description\" content=\"Conozca de primera mano nuestras vanguardistas soluciones en automatizaci\u00f3n de AT, MT y BT que est\u00e1n revolucionando el panorama energ\u00e9tico.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.zivautomation.com\/es\/news-and-events\/eventos\/middle-east-energy-2024\/\" \/>\n<meta property=\"og:site_name\" content=\"ZIV\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-04T06:00:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-09T10:34:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.zivautomation.com\/wp-content\/uploads\/2024\/04\/mee-post.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Carlos Egia Ossorio\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Carlos Egia Ossorio\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.zivautomation.com\\\/es\\\/news-and-events\\\/eventos\\\/middle-east-energy-2024\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.zivautomation.com\\\/es\\\/news-and-events\\\/eventos\\\/middle-east-energy-2024\\\/\"},\"author\":{\"name\":\"Carlos Egia Ossorio\",\"@id\":\"https:\\\/\\\/www.zivautomation.com\\\/es\\\/#\\\/schema\\\/person\\\/69fd567d7e85e0c3f6a64d5e634563f8\"},\"headline\":\"\u00a1Conozca el futuro de la automatizaci\u00f3n de la energ\u00eda en MEE &#8211; Middle East Energy 2024!\",\"datePublished\":\"2024-04-04T06:00:57+00:00\",\"dateModified\":\"2024-04-09T10:34:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.zivautomation.com\\\/es\\\/news-and-events\\\/eventos\\\/middle-east-energy-2024\\\/\"},\"wordCount\":331,\"publisher\":{\"@id\":\"https:\\\/\\\/www.zivautomation.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.zivautomation.com\\\/es\\\/news-and-events\\\/eventos\\\/middle-east-energy-2024\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.zivautomation.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/mee-post.jpg\",\"articleSection\":[\"Eventos\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.zivautomation.com\\\/es\\\/news-and-events\\\/eventos\\\/middle-east-energy-2024\\\/\",\"url\":\"https:\\\/\\\/www.zivautomation.com\\\/es\\\/news-and-events\\\/eventos\\\/middle-east-energy-2024\\\/\",\"name\":\"\u00a1Conozca el futuro de la automatizaci\u00f3n de la energ\u00eda en MEE - Middle East Energy 2024! - ZIV\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.zivautomation.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.zivautomation.com\\\/es\\\/news-and-events\\\/eventos\\\/middle-east-energy-2024\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.zivautomation.com\\\/es\\\/news-and-events\\\/eventos\\\/middle-east-energy-2024\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.zivautomation.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/mee-post.jpg\",\"datePublished\":\"2024-04-04T06:00:57+00:00\",\"dateModified\":\"2024-04-09T10:34:54+00:00\",\"description\":\"Conozca de primera mano nuestras vanguardistas soluciones en automatizaci\u00f3n de AT, MT y BT que est\u00e1n revolucionando el panorama energ\u00e9tico.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.zivautomation.com\\\/es\\\/news-and-events\\\/eventos\\\/middle-east-energy-2024\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.zivautomation.com\\\/es\\\/news-and-events\\\/eventos\\\/middle-east-energy-2024\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.zivautomation.com\\\/es\\\/news-and-events\\\/eventos\\\/middle-east-energy-2024\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.zivautomation.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/mee-post.jpg\",\"contentUrl\":\"https:\\\/\\\/www.zivautomation.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/mee-post.jpg\",\"width\":800,\"height\":400,\"caption\":\"Middle East Energy 2024\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.zivautomation.com\\\/es\\\/news-and-events\\\/eventos\\\/middle-east-energy-2024\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.zivautomation.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00a1Conozca el futuro de la automatizaci\u00f3n de la energ\u00eda en MEE &#8211; Middle East Energy 2024!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.zivautomation.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.zivautomation.com\\\/es\\\/\",\"name\":\"ZIV\",\"description\":\"Haciendo realidad la Red del Futuro\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.zivautomation.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.zivautomation.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.zivautomation.com\\\/es\\\/#organization\",\"name\":\"ZIV\",\"url\":\"https:\\\/\\\/www.zivautomation.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.zivautomation.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.zivautomation.com\\\/wp-content\\\/uploads\\\/2016\\\/10\\\/ziv_solo_cmyk_hr.jpg\",\"contentUrl\":\"https:\\\/\\\/www.zivautomation.com\\\/wp-content\\\/uploads\\\/2016\\\/10\\\/ziv_solo_cmyk_hr.jpg\",\"width\":7078,\"height\":2234,\"caption\":\"ZIV\"},\"image\":{\"@id\":\"https:\\\/\\\/www.zivautomation.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.zivautomation.com\\\/es\\\/#\\\/schema\\\/person\\\/69fd567d7e85e0c3f6a64d5e634563f8\",\"name\":\"Carlos Egia Ossorio\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00a1Conozca el futuro de la automatizaci\u00f3n de la energ\u00eda en MEE - Middle East Energy 2024! - ZIV","description":"Conozca de primera mano nuestras vanguardistas soluciones en automatizaci\u00f3n de AT, MT y BT que est\u00e1n revolucionando el panorama energ\u00e9tico.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.zivautomation.com\/es\/news-and-events\/eventos\/middle-east-energy-2024\/","og_locale":"es_ES","og_type":"article","og_title":"\u00a1Conozca el futuro de la automatizaci\u00f3n de la energ\u00eda en MEE - Middle East Energy 2024! - ZIV","og_description":"Conozca de primera mano nuestras vanguardistas soluciones en automatizaci\u00f3n de AT, MT y BT que est\u00e1n revolucionando el panorama energ\u00e9tico.","og_url":"https:\/\/www.zivautomation.com\/es\/news-and-events\/eventos\/middle-east-energy-2024\/","og_site_name":"ZIV","article_published_time":"2024-04-04T06:00:57+00:00","article_modified_time":"2024-04-09T10:34:54+00:00","og_image":[{"width":800,"height":400,"url":"https:\/\/www.zivautomation.com\/wp-content\/uploads\/2024\/04\/mee-post.jpg","type":"image\/jpeg"}],"author":"Carlos Egia Ossorio","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Carlos Egia Ossorio","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.zivautomation.com\/es\/news-and-events\/eventos\/middle-east-energy-2024\/#article","isPartOf":{"@id":"https:\/\/www.zivautomation.com\/es\/news-and-events\/eventos\/middle-east-energy-2024\/"},"author":{"name":"Carlos Egia Ossorio","@id":"https:\/\/www.zivautomation.com\/es\/#\/schema\/person\/69fd567d7e85e0c3f6a64d5e634563f8"},"headline":"\u00a1Conozca el futuro de la automatizaci\u00f3n de la energ\u00eda en MEE &#8211; Middle East Energy 2024!","datePublished":"2024-04-04T06:00:57+00:00","dateModified":"2024-04-09T10:34:54+00:00","mainEntityOfPage":{"@id":"https:\/\/www.zivautomation.com\/es\/news-and-events\/eventos\/middle-east-energy-2024\/"},"wordCount":331,"publisher":{"@id":"https:\/\/www.zivautomation.com\/es\/#organization"},"image":{"@id":"https:\/\/www.zivautomation.com\/es\/news-and-events\/eventos\/middle-east-energy-2024\/#primaryimage"},"thumbnailUrl":"https:\/\/www.zivautomation.com\/wp-content\/uploads\/2024\/04\/mee-post.jpg","articleSection":["Eventos"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.zivautomation.com\/es\/news-and-events\/eventos\/middle-east-energy-2024\/","url":"https:\/\/www.zivautomation.com\/es\/news-and-events\/eventos\/middle-east-energy-2024\/","name":"\u00a1Conozca el futuro de la automatizaci\u00f3n de la energ\u00eda en MEE - Middle East Energy 2024! - ZIV","isPartOf":{"@id":"https:\/\/www.zivautomation.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.zivautomation.com\/es\/news-and-events\/eventos\/middle-east-energy-2024\/#primaryimage"},"image":{"@id":"https:\/\/www.zivautomation.com\/es\/news-and-events\/eventos\/middle-east-energy-2024\/#primaryimage"},"thumbnailUrl":"https:\/\/www.zivautomation.com\/wp-content\/uploads\/2024\/04\/mee-post.jpg","datePublished":"2024-04-04T06:00:57+00:00","dateModified":"2024-04-09T10:34:54+00:00","description":"Conozca de primera mano nuestras vanguardistas soluciones en automatizaci\u00f3n de AT, MT y BT que est\u00e1n revolucionando el panorama energ\u00e9tico.","breadcrumb":{"@id":"https:\/\/www.zivautomation.com\/es\/news-and-events\/eventos\/middle-east-energy-2024\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.zivautomation.com\/es\/news-and-events\/eventos\/middle-east-energy-2024\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.zivautomation.com\/es\/news-and-events\/eventos\/middle-east-energy-2024\/#primaryimage","url":"https:\/\/www.zivautomation.com\/wp-content\/uploads\/2024\/04\/mee-post.jpg","contentUrl":"https:\/\/www.zivautomation.com\/wp-content\/uploads\/2024\/04\/mee-post.jpg","width":800,"height":400,"caption":"Middle East Energy 2024"},{"@type":"BreadcrumbList","@id":"https:\/\/www.zivautomation.com\/es\/news-and-events\/eventos\/middle-east-energy-2024\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.zivautomation.com\/es\/"},{"@type":"ListItem","position":2,"name":"\u00a1Conozca el futuro de la automatizaci\u00f3n de la energ\u00eda en MEE &#8211; Middle East Energy 2024!"}]},{"@type":"WebSite","@id":"https:\/\/www.zivautomation.com\/es\/#website","url":"https:\/\/www.zivautomation.com\/es\/","name":"ZIV","description":"Haciendo realidad la Red del Futuro","publisher":{"@id":"https:\/\/www.zivautomation.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.zivautomation.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.zivautomation.com\/es\/#organization","name":"ZIV","url":"https:\/\/www.zivautomation.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.zivautomation.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.zivautomation.com\/wp-content\/uploads\/2016\/10\/ziv_solo_cmyk_hr.jpg","contentUrl":"https:\/\/www.zivautomation.com\/wp-content\/uploads\/2016\/10\/ziv_solo_cmyk_hr.jpg","width":7078,"height":2234,"caption":"ZIV"},"image":{"@id":"https:\/\/www.zivautomation.com\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.zivautomation.com\/es\/#\/schema\/person\/69fd567d7e85e0c3f6a64d5e634563f8","name":"Carlos Egia Ossorio"}]}},"_links":{"self":[{"href":"https:\/\/www.zivautomation.com\/es\/wp-json\/wp\/v2\/posts\/95365","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zivautomation.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.zivautomation.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.zivautomation.com\/es\/wp-json\/wp\/v2\/users\/1324"}],"replies":[{"embeddable":true,"href":"https:\/\/www.zivautomation.com\/es\/wp-json\/wp\/v2\/comments?post=95365"}],"version-history":[{"count":8,"href":"https:\/\/www.zivautomation.com\/es\/wp-json\/wp\/v2\/posts\/95365\/revisions"}],"predecessor-version":[{"id":95445,"href":"https:\/\/www.zivautomation.com\/es\/wp-json\/wp\/v2\/posts\/95365\/revisions\/95445"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.zivautomation.com\/es\/wp-json\/wp\/v2\/media\/95367"}],"wp:attachment":[{"href":"https:\/\/www.zivautomation.com\/es\/wp-json\/wp\/v2\/media?parent=95365"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.zivautomation.com\/es\/wp-json\/wp\/v2\/categories?post=95365"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.zivautomation.com\/es\/wp-json\/wp\/v2\/tags?post=95365"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}