{"id":67845,"date":"2018-12-14T14:30:27","date_gmt":"2018-12-14T14:30:27","guid":{"rendered":"https:\/\/www.zivautomation.com\/?p=67845"},"modified":"2020-03-12T12:39:23","modified_gmt":"2020-03-12T12:39:23","slug":"ada_lovelace","status":"publish","type":"post","link":"https:\/\/www.zivautomation.com\/es\/news-and-events\/noticias\/ada_lovelace\/","title":{"rendered":"Premio al voluntariado &#8211; Ada Lovelace"},"content":{"rendered":"<div>\n<div class=\"posted-by\">\n<div class=\"publish-date\">\u00a0<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-67847 size-full\" src=\"https:\/\/www.zivautomation.com\/wp-content\/uploads\/2018\/12\/ziv_ada_lovelace_byron_room.png\" alt=\"\" width=\"1250\" height=\"350\" srcset=\"https:\/\/www.zivautomation.com\/wp-content\/uploads\/2018\/12\/ziv_ada_lovelace_byron_room.png 1250w, https:\/\/www.zivautomation.com\/wp-content\/uploads\/2018\/12\/ziv_ada_lovelace_byron_room-300x84.png 300w, https:\/\/www.zivautomation.com\/wp-content\/uploads\/2018\/12\/ziv_ada_lovelace_byron_room-768x215.png 768w, https:\/\/www.zivautomation.com\/wp-content\/uploads\/2018\/12\/ziv_ada_lovelace_byron_room-1024x287.png 1024w, https:\/\/www.zivautomation.com\/wp-content\/uploads\/2018\/12\/ziv_ada_lovelace_byron_room-672x188.png 672w, https:\/\/www.zivautomation.com\/wp-content\/uploads\/2018\/12\/ziv_ada_lovelace_byron_room-1038x291.png 1038w, https:\/\/www.zivautomation.com\/wp-content\/uploads\/2018\/12\/ziv_ada_lovelace_byron_room-339x95.png 339w\" sizes=\"auto, (max-width: 1250px) 100vw, 1250px\" \/><\/div>\n<\/div>\n<div>\n<div class=\"posted-by\">\n<div class=\"publish-date\">\n<h1>El proyecto &#8220;Inspira STEAM&#8221; en el que participa ZIV ha recibido premio al Voluntariado en el \u00e1mbito educativo que otorga la Fundaci\u00f3n Telef\u00f3nica<\/h1>\n<h2>Gracias a ello, hemos decidido poner el nombre de &#8220;Ada Lovelace&#8221; a una de las salas. \u00bfPor qu\u00e9? He aqu\u00ed la peque\u00f1a historia de c\u00f3mo dos ingenieras contagiaron su entusiasmo a toda una organizaci\u00f3n.<\/h2>\n<\/div>\n<div>\n<p style=\"text-align: center;\"><a href=\"https:\/\/prezi.com\/view\/kNMgfRip1PKagHNj1s1u\/\">-Ver la historia de la sala Ada Lovelace-<\/a><\/p>\n<p>Este a\u00f1o, dos profesionales de ZIV han participado como mentoras voluntarias en un programa promovido por la Universidad de Deusto para favorecer la vocaci\u00f3n cient\u00edfica entre las ni\u00f1as de 10 a 14 a\u00f1os. Fruto de esa experiencia el martes nos sugirieron \u201cponer el nombre de Ada Lovelace a una de las salas, ya que fue la primera programadora de la historia\u201d<\/p>\n<p>Nos pareci\u00f3 correcto, preparamos el r\u00f3tulo. Al d\u00eda siguiente pensamos, ya que hay r\u00f3tulo, podemos sacar una foto, y comunicarlo en el bolet\u00edn interno. Para no escribir algo muy extenso, pensamos en hacer una breve presentaci\u00f3n para explicar qui\u00e9n era Ada. Y en el proceso de prepararlo nos fuimos enamorando del proyecto, de la iniciativa \u201cinspira\u201d, del impacto en sus participantes y de algo llamativo y relevante: pese a pasar delante de las salas todos los d\u00edas, jam\u00e1s nos hab\u00edamos percatado de que a todas ellas les hab\u00edamos puesto nombre de hombre. S\u00ed, decidimos hace tiempo utilizar el nombre de reconocidas personas de la ciencia para organizar las salas, y solo pensamos en ellos.<\/p>\n<p>Como empresa, tenemos la percepci\u00f3n de ser paritarios y ofrecer las mismas oportunidades. Contamos con una Presidenta, una CFO y un porcentaje de altos cargos femeninos envidiable. Si bien, este detalle, nos ha hecho ver que hay muchos peque\u00f1os matices que tambi\u00e9n importan y debemos estar atentos.<\/p>\n<p>Hoy hemos dado un peque\u00f1o paso. Agradecemos a Laura y Sonia su contribuci\u00f3n.<\/p>\n<p>Los referentes importan, y mucho. D\u00e9jate entusiasmar por el proyecto inspira y los logros de Ada Lovelace \/Byron, solo te llevar\u00e1 tres minutos.<\/p>\n<p><em>PD. D\u00e9jate entusiasmar por el proyecto inspira y los logros de Ada Lovelace \/Byron, solo te llevar\u00e1 tres minutos. Al final de la presentaci\u00f3n hay un video sobre Ada Lovelace realmente interesante, En enero haremos una jornada en la que Laura y Sonia nos explicar\u00e1n su experiencia en el proyecto.\u00a0<\/em><\/p>\n<h4>El programa &#8220;Inspira STEAM&#8221;<\/h4>\n<p>El proyecto\u00a0<a href=\"http:\/\/inspirasteam.net\/\">Inspira Steam<\/a>, con el que la Universidad de Deusto aspira a fomentar la vocaci\u00f3n cient\u00edfico-tecnol\u00f3gica entre las estudiantes de primaria ha ganado el premio a la mejor propuesta educativa en la primera edici\u00f3n de los Premios Fundaci\u00f3n Telef\u00f3nica al Voluntariado, un proyecto de Fundaci\u00f3n Telef\u00f3nica en su 20\u00ba aniversario para reconocer y agradecer el valor que el voluntariado aporta a la sociedad. Inspira Steam es una iniciativa pionera en el Pa\u00eds Vasco basado en acciones de sensibilizaci\u00f3n y orientaci\u00f3n, que imparten mujeres profesionales del mundo de la investigaci\u00f3n, la ciencia y la tecnolog\u00eda.<\/p>\n<p>Inspira Steam utiliza por primera vez la t\u00e9cnica del mentoring grupal en un proyecto de fomento de las STEAM (Science, Technology, Engineering, Arts and Maths) entre estudiantes de primaria. En esta iniciativa promovida por la Universidad de Deusto cuenta con la colaboraci\u00f3n de Innobasque y la financiaci\u00f3n de las tres diputaciones forales: Bizkaia, Gipuzkoa y \u00c1lava, adem\u00e1s de BBK y Roche. Inspira Steam recibir\u00e1 gracias a este premio una dotaci\u00f3n de 5.000 euros que deber\u00e1 revertir en su proyecto.<\/p>\n<p><a href=\"http:\/\/inspirasteam.net\/mentoras\/bizkaia\/\">http:\/\/inspirasteam.net\/mentoras\/bizkaia\/<\/a><\/p>\n<h4>Premio Fundaci\u00f3n Telef\u00f3nica<\/h4>\n<p>En su 20\u00b0 aniversario, Fundaci\u00f3n Telef\u00f3nica quiere reconocer y agradecer el valor que el voluntariado aporta a la sociedad. Para ello, ha creado los Premios Fundaci\u00f3n Telef\u00f3nica al Voluntariado, cuyo objetivo es sensibilizar e incentivar la acci\u00f3n voluntaria, as\u00ed como servir de catalizadores de las iniciativas del voluntariado en Espa\u00f1a.<\/p>\n<p><a href=\"https:\/\/www.fundaciontelefonica.com\/voluntarios\/premios\/\">https:\/\/www.fundaciontelefonica.com\/voluntarios\/premios\/<\/a><\/p>\n<\/div>\n<\/div>\n<\/div>\n<div>\n<p style=\"text-align: center;\">\n<\/div>\n<p>&nbsp;<\/p>\n<\/div>\n<div>\n<p>&nbsp;<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 El proyecto &#8220;Inspira STEAM&#8221; en el que participa ZIV ha recibido premio al Voluntariado en el \u00e1mbito educativo que otorga la Fundaci\u00f3n Telef\u00f3nica Gracias a ello, hemos decidido poner el nombre de &#8220;Ada Lovelace&#8221; a una de las salas. \u00bfPor qu\u00e9? He aqu\u00ed la peque\u00f1a historia de c\u00f3mo dos ingenieras contagiaron su entusiasmo a toda una organizaci\u00f3n. -Ver la [&hellip;]<\/p>\n","protected":false},"author":1323,"featured_media":73998,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","footnotes":""},"categories":[94],"tags":[161],"class_list":["post-67845","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-events-2-es"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Premio al voluntariado - Ada Lovelace - ZIV Inspira STEAM<\/title>\n<meta name=\"description\" content=\"El proyecto &quot;Inspira STEAM&quot; en el que participa ZIV ha recibido premio al Voluntariado en el \u00e1mbito educativo que otorga la Fundaci\u00f3n Telef\u00f3nica\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.zivautomation.com\/es\/news-and-events\/noticias\/ada_lovelace\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Premio al voluntariado - Ada Lovelace - ZIV Inspira STEAM\" \/>\n<meta property=\"og:description\" content=\"El proyecto &quot;Inspira STEAM&quot; en el que participa ZIV ha recibido premio al Voluntariado en el \u00e1mbito educativo que otorga la Fundaci\u00f3n Telef\u00f3nica\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.zivautomation.com\/es\/news-and-events\/noticias\/ada_lovelace\/\" \/>\n<meta property=\"og:site_name\" content=\"ZIV\" \/>\n<meta property=\"article:published_time\" content=\"2018-12-14T14:30:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-03-12T12:39:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.zivautomation.com\/wp-content\/uploads\/2018\/12\/ziv-corporate-news-noticias-corporativas.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Itziar Lasaosa Torrontegi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Itziar Lasaosa Torrontegi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.zivautomation.com\\\/es\\\/news-and-events\\\/noticias\\\/ada_lovelace\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.zivautomation.com\\\/es\\\/news-and-events\\\/noticias\\\/ada_lovelace\\\/\"},\"author\":{\"name\":\"Itziar Lasaosa Torrontegi\",\"@id\":\"https:\\\/\\\/www.zivautomation.com\\\/es\\\/#\\\/schema\\\/person\\\/f7f80341f66f0eff7766606026a17a4d\"},\"headline\":\"Premio al voluntariado &#8211; Ada Lovelace\",\"datePublished\":\"2018-12-14T14:30:27+00:00\",\"dateModified\":\"2020-03-12T12:39:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.zivautomation.com\\\/es\\\/news-and-events\\\/noticias\\\/ada_lovelace\\\/\"},\"wordCount\":673,\"publisher\":{\"@id\":\"https:\\\/\\\/www.zivautomation.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.zivautomation.com\\\/es\\\/news-and-events\\\/noticias\\\/ada_lovelace\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.zivautomation.com\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/ziv-corporate-news-noticias-corporativas.png\",\"keywords\":[\"Events\"],\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.zivautomation.com\\\/es\\\/news-and-events\\\/noticias\\\/ada_lovelace\\\/\",\"url\":\"https:\\\/\\\/www.zivautomation.com\\\/es\\\/news-and-events\\\/noticias\\\/ada_lovelace\\\/\",\"name\":\"Premio al voluntariado - Ada Lovelace - ZIV Inspira STEAM\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.zivautomation.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.zivautomation.com\\\/es\\\/news-and-events\\\/noticias\\\/ada_lovelace\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.zivautomation.com\\\/es\\\/news-and-events\\\/noticias\\\/ada_lovelace\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.zivautomation.com\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/ziv-corporate-news-noticias-corporativas.png\",\"datePublished\":\"2018-12-14T14:30:27+00:00\",\"dateModified\":\"2020-03-12T12:39:23+00:00\",\"description\":\"El proyecto \\\"Inspira STEAM\\\" en el que participa ZIV ha recibido premio al Voluntariado en el \u00e1mbito educativo que otorga la Fundaci\u00f3n Telef\u00f3nica\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.zivautomation.com\\\/es\\\/news-and-events\\\/noticias\\\/ada_lovelace\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.zivautomation.com\\\/es\\\/news-and-events\\\/noticias\\\/ada_lovelace\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.zivautomation.com\\\/es\\\/news-and-events\\\/noticias\\\/ada_lovelace\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.zivautomation.com\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/ziv-corporate-news-noticias-corporativas.png\",\"contentUrl\":\"https:\\\/\\\/www.zivautomation.com\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/ziv-corporate-news-noticias-corporativas.png\",\"width\":800,\"height\":400,\"caption\":\"noticias corpotativas - ZIV - Corporate news\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.zivautomation.com\\\/es\\\/news-and-events\\\/noticias\\\/ada_lovelace\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.zivautomation.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Premio al voluntariado &#8211; Ada Lovelace\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.zivautomation.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.zivautomation.com\\\/es\\\/\",\"name\":\"ZIV\",\"description\":\"Haciendo realidad la Red del Futuro\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.zivautomation.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.zivautomation.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.zivautomation.com\\\/es\\\/#organization\",\"name\":\"ZIV\",\"url\":\"https:\\\/\\\/www.zivautomation.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.zivautomation.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.zivautomation.com\\\/wp-content\\\/uploads\\\/2016\\\/10\\\/ziv_solo_cmyk_hr.jpg\",\"contentUrl\":\"https:\\\/\\\/www.zivautomation.com\\\/wp-content\\\/uploads\\\/2016\\\/10\\\/ziv_solo_cmyk_hr.jpg\",\"width\":7078,\"height\":2234,\"caption\":\"ZIV\"},\"image\":{\"@id\":\"https:\\\/\\\/www.zivautomation.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.zivautomation.com\\\/es\\\/#\\\/schema\\\/person\\\/f7f80341f66f0eff7766606026a17a4d\",\"name\":\"Itziar Lasaosa Torrontegi\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Premio al voluntariado - Ada Lovelace - ZIV Inspira STEAM","description":"El proyecto \"Inspira STEAM\" en el que participa ZIV ha recibido premio al Voluntariado en el \u00e1mbito educativo que otorga la Fundaci\u00f3n Telef\u00f3nica","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.zivautomation.com\/es\/news-and-events\/noticias\/ada_lovelace\/","og_locale":"es_ES","og_type":"article","og_title":"Premio al voluntariado - Ada Lovelace - ZIV Inspira STEAM","og_description":"El proyecto \"Inspira STEAM\" en el que participa ZIV ha recibido premio al Voluntariado en el \u00e1mbito educativo que otorga la Fundaci\u00f3n Telef\u00f3nica","og_url":"https:\/\/www.zivautomation.com\/es\/news-and-events\/noticias\/ada_lovelace\/","og_site_name":"ZIV","article_published_time":"2018-12-14T14:30:27+00:00","article_modified_time":"2020-03-12T12:39:23+00:00","og_image":[{"width":800,"height":400,"url":"https:\/\/www.zivautomation.com\/wp-content\/uploads\/2018\/12\/ziv-corporate-news-noticias-corporativas.png","type":"image\/png"}],"author":"Itziar Lasaosa Torrontegi","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Itziar Lasaosa Torrontegi","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.zivautomation.com\/es\/news-and-events\/noticias\/ada_lovelace\/#article","isPartOf":{"@id":"https:\/\/www.zivautomation.com\/es\/news-and-events\/noticias\/ada_lovelace\/"},"author":{"name":"Itziar Lasaosa Torrontegi","@id":"https:\/\/www.zivautomation.com\/es\/#\/schema\/person\/f7f80341f66f0eff7766606026a17a4d"},"headline":"Premio al voluntariado &#8211; Ada Lovelace","datePublished":"2018-12-14T14:30:27+00:00","dateModified":"2020-03-12T12:39:23+00:00","mainEntityOfPage":{"@id":"https:\/\/www.zivautomation.com\/es\/news-and-events\/noticias\/ada_lovelace\/"},"wordCount":673,"publisher":{"@id":"https:\/\/www.zivautomation.com\/es\/#organization"},"image":{"@id":"https:\/\/www.zivautomation.com\/es\/news-and-events\/noticias\/ada_lovelace\/#primaryimage"},"thumbnailUrl":"https:\/\/www.zivautomation.com\/wp-content\/uploads\/2018\/12\/ziv-corporate-news-noticias-corporativas.png","keywords":["Events"],"articleSection":["Noticias"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.zivautomation.com\/es\/news-and-events\/noticias\/ada_lovelace\/","url":"https:\/\/www.zivautomation.com\/es\/news-and-events\/noticias\/ada_lovelace\/","name":"Premio al voluntariado - Ada Lovelace - ZIV Inspira STEAM","isPartOf":{"@id":"https:\/\/www.zivautomation.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.zivautomation.com\/es\/news-and-events\/noticias\/ada_lovelace\/#primaryimage"},"image":{"@id":"https:\/\/www.zivautomation.com\/es\/news-and-events\/noticias\/ada_lovelace\/#primaryimage"},"thumbnailUrl":"https:\/\/www.zivautomation.com\/wp-content\/uploads\/2018\/12\/ziv-corporate-news-noticias-corporativas.png","datePublished":"2018-12-14T14:30:27+00:00","dateModified":"2020-03-12T12:39:23+00:00","description":"El proyecto \"Inspira STEAM\" en el que participa ZIV ha recibido premio al Voluntariado en el \u00e1mbito educativo que otorga la Fundaci\u00f3n Telef\u00f3nica","breadcrumb":{"@id":"https:\/\/www.zivautomation.com\/es\/news-and-events\/noticias\/ada_lovelace\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.zivautomation.com\/es\/news-and-events\/noticias\/ada_lovelace\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.zivautomation.com\/es\/news-and-events\/noticias\/ada_lovelace\/#primaryimage","url":"https:\/\/www.zivautomation.com\/wp-content\/uploads\/2018\/12\/ziv-corporate-news-noticias-corporativas.png","contentUrl":"https:\/\/www.zivautomation.com\/wp-content\/uploads\/2018\/12\/ziv-corporate-news-noticias-corporativas.png","width":800,"height":400,"caption":"noticias corpotativas - ZIV - Corporate news"},{"@type":"BreadcrumbList","@id":"https:\/\/www.zivautomation.com\/es\/news-and-events\/noticias\/ada_lovelace\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.zivautomation.com\/es\/"},{"@type":"ListItem","position":2,"name":"Premio al voluntariado &#8211; Ada Lovelace"}]},{"@type":"WebSite","@id":"https:\/\/www.zivautomation.com\/es\/#website","url":"https:\/\/www.zivautomation.com\/es\/","name":"ZIV","description":"Haciendo realidad la Red del Futuro","publisher":{"@id":"https:\/\/www.zivautomation.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.zivautomation.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.zivautomation.com\/es\/#organization","name":"ZIV","url":"https:\/\/www.zivautomation.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.zivautomation.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.zivautomation.com\/wp-content\/uploads\/2016\/10\/ziv_solo_cmyk_hr.jpg","contentUrl":"https:\/\/www.zivautomation.com\/wp-content\/uploads\/2016\/10\/ziv_solo_cmyk_hr.jpg","width":7078,"height":2234,"caption":"ZIV"},"image":{"@id":"https:\/\/www.zivautomation.com\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.zivautomation.com\/es\/#\/schema\/person\/f7f80341f66f0eff7766606026a17a4d","name":"Itziar Lasaosa Torrontegi"}]}},"_links":{"self":[{"href":"https:\/\/www.zivautomation.com\/es\/wp-json\/wp\/v2\/posts\/67845","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zivautomation.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.zivautomation.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.zivautomation.com\/es\/wp-json\/wp\/v2\/users\/1323"}],"replies":[{"embeddable":true,"href":"https:\/\/www.zivautomation.com\/es\/wp-json\/wp\/v2\/comments?post=67845"}],"version-history":[{"count":13,"href":"https:\/\/www.zivautomation.com\/es\/wp-json\/wp\/v2\/posts\/67845\/revisions"}],"predecessor-version":[{"id":69722,"href":"https:\/\/www.zivautomation.com\/es\/wp-json\/wp\/v2\/posts\/67845\/revisions\/69722"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.zivautomation.com\/es\/wp-json\/wp\/v2\/media\/73998"}],"wp:attachment":[{"href":"https:\/\/www.zivautomation.com\/es\/wp-json\/wp\/v2\/media?parent=67845"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.zivautomation.com\/es\/wp-json\/wp\/v2\/categories?post=67845"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.zivautomation.com\/es\/wp-json\/wp\/v2\/tags?post=67845"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}