{"id":66183,"date":"2018-07-12T10:42:34","date_gmt":"2018-07-12T10:42:34","guid":{"rendered":"https:\/\/www.zivautomation.com\/?p=66183"},"modified":"2020-03-17T11:39:36","modified_gmt":"2020-03-17T11:39:36","slug":"unesa-ceoe","status":"publish","type":"post","link":"https:\/\/www.zivautomation.com\/es\/news-and-events\/noticias\/unesa-ceoe\/","title":{"rendered":"Las redes el\u00e9ctricas del futuro: un reto industrial"},"content":{"rendered":"<div>\n<div class=\"posted-by\">\n<div class=\"publish-date\">\n<h2><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-66196 size-full\" src=\"https:\/\/www.zivautomation.com\/wp-content\/uploads\/2018\/07\/ziv_unesa_esp.png\" alt=\"\" width=\"1250\" height=\"350\" srcset=\"https:\/\/www.zivautomation.com\/wp-content\/uploads\/2018\/07\/ziv_unesa_esp.png 1250w, https:\/\/www.zivautomation.com\/wp-content\/uploads\/2018\/07\/ziv_unesa_esp-300x84.png 300w, https:\/\/www.zivautomation.com\/wp-content\/uploads\/2018\/07\/ziv_unesa_esp-768x215.png 768w, https:\/\/www.zivautomation.com\/wp-content\/uploads\/2018\/07\/ziv_unesa_esp-1024x287.png 1024w, https:\/\/www.zivautomation.com\/wp-content\/uploads\/2018\/07\/ziv_unesa_esp-672x188.png 672w, https:\/\/www.zivautomation.com\/wp-content\/uploads\/2018\/07\/ziv_unesa_esp-1038x291.png 1038w\" sizes=\"auto, (max-width: 1250px) 100vw, 1250px\" \/><\/h2>\n<h2>ZIV contribuye a la modernizaci\u00f3n de la industria<\/h2>\n<p>&nbsp;<\/p>\n<p>ZIV particip\u00f3 ayer en la jornada organizada por UNESA y CEOE (Confederaci\u00f3n Espa\u00f1ola de Organizaciones Empresariales) para compartir su visi\u00f3n en cuanto a la contribuci\u00f3n de las empresas del sector a fortalecer y modernizar la industria.\u00a0El Sr.Yarza (Responsable de desarrollo de negocio SAS de ZIV) anim\u00f3 a las instituciones y compa\u00f1\u00edas el\u00e9ctricas asistentes a favorecer las grandes proyectos, por el valor que generan a la industria en su conjunto, no solo en t\u00e9rminos monetarios, sino sobre todo, porque son cruciales para potenciar el desarrollo tecnol\u00f3gico y generar referencias de valor internacional.<\/p>\n<\/div>\n<div><\/div>\n<div class=\"publish-date\">\n<p>Yarza se\u00f1al\u00f3 que &#8220;en el caso de ZIV, han supuesto una palanca determinante, que permite a la empresa presentar internacionalmente soluciones fiables y una capacidad de desarrollo tecnol\u00f3gico y adaptaci\u00f3n demostrables&#8221;. Finaliz\u00f3 su ponencia aportando datos clave: 500 empleos, 25 a\u00f1os de experiencia en el sector, una inversi\u00f3n continuada en i+d de entorno al 10% y referencias en 85 pa\u00edses.<\/p>\n<h4><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-66197 aligncenter\" src=\"https:\/\/www.zivautomation.com\/wp-content\/uploads\/2018\/07\/ziv_unesa_yarza-1024x768.jpeg\" alt=\"\" width=\"1024\" height=\"768\" srcset=\"https:\/\/www.zivautomation.com\/wp-content\/uploads\/2018\/07\/ziv_unesa_yarza-1024x768.jpeg 1024w, https:\/\/www.zivautomation.com\/wp-content\/uploads\/2018\/07\/ziv_unesa_yarza-300x225.jpeg 300w, https:\/\/www.zivautomation.com\/wp-content\/uploads\/2018\/07\/ziv_unesa_yarza-768x576.jpeg 768w, https:\/\/www.zivautomation.com\/wp-content\/uploads\/2018\/07\/ziv_unesa_yarza-672x504.jpeg 672w, https:\/\/www.zivautomation.com\/wp-content\/uploads\/2018\/07\/ziv_unesa_yarza-777x583.jpeg 777w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/h4>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-66189 aligncenter\" src=\"https:\/\/www.zivautomation.com\/wp-content\/uploads\/2018\/07\/ziv_jornada_unesa-1024x760.png\" alt=\"\" width=\"1024\" height=\"760\" srcset=\"https:\/\/www.zivautomation.com\/wp-content\/uploads\/2018\/07\/ziv_jornada_unesa-1024x760.png 1024w, https:\/\/www.zivautomation.com\/wp-content\/uploads\/2018\/07\/ziv_jornada_unesa-300x223.png 300w, https:\/\/www.zivautomation.com\/wp-content\/uploads\/2018\/07\/ziv_jornada_unesa-768x570.png 768w, https:\/\/www.zivautomation.com\/wp-content\/uploads\/2018\/07\/ziv_jornada_unesa-672x498.png 672w, https:\/\/www.zivautomation.com\/wp-content\/uploads\/2018\/07\/ziv_jornada_unesa-786x583.png 786w, https:\/\/www.zivautomation.com\/wp-content\/uploads\/2018\/07\/ziv_jornada_unesa.png 1146w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<h4><\/h4>\n<\/div>\n<\/div>\n<div><\/div>\n<\/div>\n<div>\n<p>&nbsp;<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>ZIV contribuye a la modernizaci\u00f3n de la industria &nbsp; ZIV particip\u00f3 ayer en la jornada organizada por UNESA y CEOE (Confederaci\u00f3n Espa\u00f1ola de Organizaciones Empresariales) para compartir su visi\u00f3n en cuanto a la contribuci\u00f3n de las empresas del sector a fortalecer y modernizar la industria.\u00a0El Sr.Yarza (Responsable de desarrollo de negocio SAS de ZIV) anim\u00f3 a las instituciones y compa\u00f1\u00edas [&hellip;]<\/p>\n","protected":false},"author":1323,"featured_media":73998,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","footnotes":""},"categories":[94],"tags":[161],"class_list":["post-66183","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-events-2-es"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Las redes el\u00e9ctricas del futuro: un reto industrial - ZIV<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.zivautomation.com\/es\/news-and-events\/noticias\/unesa-ceoe\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Las redes el\u00e9ctricas del futuro: un reto industrial - ZIV\" \/>\n<meta property=\"og:description\" content=\"ZIV contribuye a la modernizaci\u00f3n de la industria &nbsp; ZIV particip\u00f3 ayer en la jornada organizada por UNESA y CEOE (Confederaci\u00f3n Espa\u00f1ola de Organizaciones Empresariales) para compartir su visi\u00f3n en cuanto a la contribuci\u00f3n de las empresas del sector a fortalecer y modernizar la industria.\u00a0El Sr.Yarza (Responsable de desarrollo de negocio SAS de ZIV) anim\u00f3 a las instituciones y compa\u00f1\u00edas [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.zivautomation.com\/es\/news-and-events\/noticias\/unesa-ceoe\/\" \/>\n<meta property=\"og:site_name\" content=\"ZIV\" \/>\n<meta property=\"article:published_time\" content=\"2018-07-12T10:42:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-03-17T11:39:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.zivautomation.com\/wp-content\/uploads\/2018\/12\/ziv-corporate-news-noticias-corporativas.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Itziar Lasaosa Torrontegi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Itziar Lasaosa Torrontegi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.zivautomation.com\\\/es\\\/news-and-events\\\/noticias\\\/unesa-ceoe\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.zivautomation.com\\\/es\\\/news-and-events\\\/noticias\\\/unesa-ceoe\\\/\"},\"author\":{\"name\":\"Itziar Lasaosa Torrontegi\",\"@id\":\"https:\\\/\\\/www.zivautomation.com\\\/es\\\/#\\\/schema\\\/person\\\/f7f80341f66f0eff7766606026a17a4d\"},\"headline\":\"Las redes el\u00e9ctricas del futuro: un reto industrial\",\"datePublished\":\"2018-07-12T10:42:34+00:00\",\"dateModified\":\"2020-03-17T11:39:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.zivautomation.com\\\/es\\\/news-and-events\\\/noticias\\\/unesa-ceoe\\\/\"},\"wordCount\":184,\"publisher\":{\"@id\":\"https:\\\/\\\/www.zivautomation.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.zivautomation.com\\\/es\\\/news-and-events\\\/noticias\\\/unesa-ceoe\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.zivautomation.com\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/ziv-corporate-news-noticias-corporativas.png\",\"keywords\":[\"Events\"],\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.zivautomation.com\\\/es\\\/news-and-events\\\/noticias\\\/unesa-ceoe\\\/\",\"url\":\"https:\\\/\\\/www.zivautomation.com\\\/es\\\/news-and-events\\\/noticias\\\/unesa-ceoe\\\/\",\"name\":\"Las redes el\u00e9ctricas del futuro: un reto industrial - ZIV\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.zivautomation.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.zivautomation.com\\\/es\\\/news-and-events\\\/noticias\\\/unesa-ceoe\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.zivautomation.com\\\/es\\\/news-and-events\\\/noticias\\\/unesa-ceoe\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.zivautomation.com\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/ziv-corporate-news-noticias-corporativas.png\",\"datePublished\":\"2018-07-12T10:42:34+00:00\",\"dateModified\":\"2020-03-17T11:39:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.zivautomation.com\\\/es\\\/news-and-events\\\/noticias\\\/unesa-ceoe\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.zivautomation.com\\\/es\\\/news-and-events\\\/noticias\\\/unesa-ceoe\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.zivautomation.com\\\/es\\\/news-and-events\\\/noticias\\\/unesa-ceoe\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.zivautomation.com\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/ziv-corporate-news-noticias-corporativas.png\",\"contentUrl\":\"https:\\\/\\\/www.zivautomation.com\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/ziv-corporate-news-noticias-corporativas.png\",\"width\":800,\"height\":400,\"caption\":\"noticias corpotativas - ZIV - Corporate news\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.zivautomation.com\\\/es\\\/news-and-events\\\/noticias\\\/unesa-ceoe\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.zivautomation.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Las redes el\u00e9ctricas del futuro: un reto industrial\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.zivautomation.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.zivautomation.com\\\/es\\\/\",\"name\":\"ZIV\",\"description\":\"Haciendo realidad la Red del Futuro\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.zivautomation.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.zivautomation.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.zivautomation.com\\\/es\\\/#organization\",\"name\":\"ZIV\",\"url\":\"https:\\\/\\\/www.zivautomation.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.zivautomation.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.zivautomation.com\\\/wp-content\\\/uploads\\\/2016\\\/10\\\/ziv_solo_cmyk_hr.jpg\",\"contentUrl\":\"https:\\\/\\\/www.zivautomation.com\\\/wp-content\\\/uploads\\\/2016\\\/10\\\/ziv_solo_cmyk_hr.jpg\",\"width\":7078,\"height\":2234,\"caption\":\"ZIV\"},\"image\":{\"@id\":\"https:\\\/\\\/www.zivautomation.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.zivautomation.com\\\/es\\\/#\\\/schema\\\/person\\\/f7f80341f66f0eff7766606026a17a4d\",\"name\":\"Itziar Lasaosa Torrontegi\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Las redes el\u00e9ctricas del futuro: un reto industrial - ZIV","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.zivautomation.com\/es\/news-and-events\/noticias\/unesa-ceoe\/","og_locale":"es_ES","og_type":"article","og_title":"Las redes el\u00e9ctricas del futuro: un reto industrial - ZIV","og_description":"ZIV contribuye a la modernizaci\u00f3n de la industria &nbsp; ZIV particip\u00f3 ayer en la jornada organizada por UNESA y CEOE (Confederaci\u00f3n Espa\u00f1ola de Organizaciones Empresariales) para compartir su visi\u00f3n en cuanto a la contribuci\u00f3n de las empresas del sector a fortalecer y modernizar la industria.\u00a0El Sr.Yarza (Responsable de desarrollo de negocio SAS de ZIV) anim\u00f3 a las instituciones y compa\u00f1\u00edas [&hellip;]","og_url":"https:\/\/www.zivautomation.com\/es\/news-and-events\/noticias\/unesa-ceoe\/","og_site_name":"ZIV","article_published_time":"2018-07-12T10:42:34+00:00","article_modified_time":"2020-03-17T11:39:36+00:00","og_image":[{"width":800,"height":400,"url":"https:\/\/www.zivautomation.com\/wp-content\/uploads\/2018\/12\/ziv-corporate-news-noticias-corporativas.png","type":"image\/png"}],"author":"Itziar Lasaosa Torrontegi","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Itziar Lasaosa Torrontegi","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.zivautomation.com\/es\/news-and-events\/noticias\/unesa-ceoe\/#article","isPartOf":{"@id":"https:\/\/www.zivautomation.com\/es\/news-and-events\/noticias\/unesa-ceoe\/"},"author":{"name":"Itziar Lasaosa Torrontegi","@id":"https:\/\/www.zivautomation.com\/es\/#\/schema\/person\/f7f80341f66f0eff7766606026a17a4d"},"headline":"Las redes el\u00e9ctricas del futuro: un reto industrial","datePublished":"2018-07-12T10:42:34+00:00","dateModified":"2020-03-17T11:39:36+00:00","mainEntityOfPage":{"@id":"https:\/\/www.zivautomation.com\/es\/news-and-events\/noticias\/unesa-ceoe\/"},"wordCount":184,"publisher":{"@id":"https:\/\/www.zivautomation.com\/es\/#organization"},"image":{"@id":"https:\/\/www.zivautomation.com\/es\/news-and-events\/noticias\/unesa-ceoe\/#primaryimage"},"thumbnailUrl":"https:\/\/www.zivautomation.com\/wp-content\/uploads\/2018\/12\/ziv-corporate-news-noticias-corporativas.png","keywords":["Events"],"articleSection":["Noticias"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.zivautomation.com\/es\/news-and-events\/noticias\/unesa-ceoe\/","url":"https:\/\/www.zivautomation.com\/es\/news-and-events\/noticias\/unesa-ceoe\/","name":"Las redes el\u00e9ctricas del futuro: un reto industrial - ZIV","isPartOf":{"@id":"https:\/\/www.zivautomation.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.zivautomation.com\/es\/news-and-events\/noticias\/unesa-ceoe\/#primaryimage"},"image":{"@id":"https:\/\/www.zivautomation.com\/es\/news-and-events\/noticias\/unesa-ceoe\/#primaryimage"},"thumbnailUrl":"https:\/\/www.zivautomation.com\/wp-content\/uploads\/2018\/12\/ziv-corporate-news-noticias-corporativas.png","datePublished":"2018-07-12T10:42:34+00:00","dateModified":"2020-03-17T11:39:36+00:00","breadcrumb":{"@id":"https:\/\/www.zivautomation.com\/es\/news-and-events\/noticias\/unesa-ceoe\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.zivautomation.com\/es\/news-and-events\/noticias\/unesa-ceoe\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.zivautomation.com\/es\/news-and-events\/noticias\/unesa-ceoe\/#primaryimage","url":"https:\/\/www.zivautomation.com\/wp-content\/uploads\/2018\/12\/ziv-corporate-news-noticias-corporativas.png","contentUrl":"https:\/\/www.zivautomation.com\/wp-content\/uploads\/2018\/12\/ziv-corporate-news-noticias-corporativas.png","width":800,"height":400,"caption":"noticias corpotativas - ZIV - Corporate news"},{"@type":"BreadcrumbList","@id":"https:\/\/www.zivautomation.com\/es\/news-and-events\/noticias\/unesa-ceoe\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.zivautomation.com\/es\/"},{"@type":"ListItem","position":2,"name":"Las redes el\u00e9ctricas del futuro: un reto industrial"}]},{"@type":"WebSite","@id":"https:\/\/www.zivautomation.com\/es\/#website","url":"https:\/\/www.zivautomation.com\/es\/","name":"ZIV","description":"Haciendo realidad la Red del Futuro","publisher":{"@id":"https:\/\/www.zivautomation.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.zivautomation.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.zivautomation.com\/es\/#organization","name":"ZIV","url":"https:\/\/www.zivautomation.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.zivautomation.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.zivautomation.com\/wp-content\/uploads\/2016\/10\/ziv_solo_cmyk_hr.jpg","contentUrl":"https:\/\/www.zivautomation.com\/wp-content\/uploads\/2016\/10\/ziv_solo_cmyk_hr.jpg","width":7078,"height":2234,"caption":"ZIV"},"image":{"@id":"https:\/\/www.zivautomation.com\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.zivautomation.com\/es\/#\/schema\/person\/f7f80341f66f0eff7766606026a17a4d","name":"Itziar Lasaosa Torrontegi"}]}},"_links":{"self":[{"href":"https:\/\/www.zivautomation.com\/es\/wp-json\/wp\/v2\/posts\/66183","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zivautomation.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.zivautomation.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.zivautomation.com\/es\/wp-json\/wp\/v2\/users\/1323"}],"replies":[{"embeddable":true,"href":"https:\/\/www.zivautomation.com\/es\/wp-json\/wp\/v2\/comments?post=66183"}],"version-history":[{"count":7,"href":"https:\/\/www.zivautomation.com\/es\/wp-json\/wp\/v2\/posts\/66183\/revisions"}],"predecessor-version":[{"id":74099,"href":"https:\/\/www.zivautomation.com\/es\/wp-json\/wp\/v2\/posts\/66183\/revisions\/74099"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.zivautomation.com\/es\/wp-json\/wp\/v2\/media\/73998"}],"wp:attachment":[{"href":"https:\/\/www.zivautomation.com\/es\/wp-json\/wp\/v2\/media?parent=66183"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.zivautomation.com\/es\/wp-json\/wp\/v2\/categories?post=66183"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.zivautomation.com\/es\/wp-json\/wp\/v2\/tags?post=66183"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}